{"id":774,"count":3,"description":"","link":"https:\/\/blogs.acu.edu\/artanddesign\/category\/websites\/","name":"Websites","slug":"websites","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/blogs.acu.edu\/artanddesign\/wp-json\/wp\/v2\/categories\/774","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.acu.edu\/artanddesign\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/blogs.acu.edu\/artanddesign\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/blogs.acu.edu\/artanddesign\/wp-json\/wp\/v2\/posts?categories=774"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}