{"id":1816,"date":"2011-04-05T10:36:55","date_gmt":"2011-04-05T15:36:55","guid":{"rendered":"http:\/\/blogs.acu.edu\/artanddesign\/files\/2011\/04\/suiteartfair.jpg"},"modified":"2011-04-05T10:36:55","modified_gmt":"2011-04-05T15:36:55","slug":"suiteartfair","status":"inherit","type":"attachment","link":"https:\/\/blogs.acu.edu\/artanddesign\/2011\/04\/05\/suite-art-fair-dallas\/suiteartfair\/","title":{"rendered":"suiteartfair"},"author":1234,"featured_media":0,"comment_status":"open","ping_status":"open","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"class_list":["post-1816","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/blogs.acu.edu\/artanddesign\/files\/2011\/04\/suiteartfair.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"229\" height=\"160\" src=\"https:\/\/blogs.acu.edu\/artanddesign\/files\/2011\/04\/suiteartfair-229x160.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/blogs.acu.edu\/artanddesign\/files\/2011\/04\/suiteartfair-229x160.jpg 229w, https:\/\/blogs.acu.edu\/artanddesign\/files\/2011\/04\/suiteartfair-150x104.jpg 150w, https:\/\/blogs.acu.edu\/artanddesign\/files\/2011\/04\/suiteartfair.jpg 450w\" sizes=\"(max-width: 229px) 100vw, 229px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":"450","height":"314","hwstring_small":"height='89' width='128'","file":"2011\/04\/suiteartfair.jpg","sizes":{"thumbnail":{"file":"suiteartfair-150x104.jpg","width":"150","height":"104","source_url":"https:\/\/blogs.acu.edu\/artanddesign\/files\/2011\/04\/suiteartfair-150x104.jpg"},"medium":{"file":"suiteartfair-229x160.jpg","width":"229","height":"160","source_url":"https:\/\/blogs.acu.edu\/artanddesign\/files\/2011\/04\/suiteartfair-229x160.jpg"},"post-thumbnail":{"file":"suiteartfair-60x60.jpg","width":"60","height":"60","source_url":"https:\/\/blogs.acu.edu\/artanddesign\/files\/2011\/04\/suiteartfair-60x60.jpg"},"full":{"file":"suiteartfair.jpg","width":450,"height":314,"mime_type":"image\/jpeg","source_url":"https:\/\/blogs.acu.edu\/artanddesign\/files\/2011\/04\/suiteartfair.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":""}},"post":1815,"source_url":"https:\/\/blogs.acu.edu\/artanddesign\/files\/2011\/04\/suiteartfair.jpg","_links":{"self":[{"href":"https:\/\/blogs.acu.edu\/artanddesign\/wp-json\/wp\/v2\/media\/1816","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.acu.edu\/artanddesign\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/blogs.acu.edu\/artanddesign\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.acu.edu\/artanddesign\/wp-json\/wp\/v2\/users\/1234"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.acu.edu\/artanddesign\/wp-json\/wp\/v2\/comments?post=1816"}]}}